{"id":875,"count":1,"description":"","link":"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/","name":"Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria","slug":"beneficios-da-visao-artificial-na-industria","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria - Blog AF Braco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria - Blog AF Braco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AF Braco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/\",\"url\":\"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/\",\"name\":\"Arquivo de Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria - Blog AF Braco\",\"isPartOf\":{\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.afbraco.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/#website\",\"url\":\"https:\/\/www.afbraco.com.br\/blog\/\",\"name\":\"Blog AF Braco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.afbraco.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/#organization\",\"name\":\"Blog AF Braco\",\"url\":\"https:\/\/www.afbraco.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.afbraco.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-5.png\",\"contentUrl\":\"https:\/\/www.afbraco.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-5.png\",\"width\":830,\"height\":234,\"caption\":\"Blog AF Braco\"},\"image\":{\"@id\":\"https:\/\/www.afbraco.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria - Blog AF Braco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria - Blog AF Braco","og_url":"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/","og_site_name":"Blog AF Braco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/","url":"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/","name":"Arquivo de Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria - Blog AF Braco","isPartOf":{"@id":"https:\/\/www.afbraco.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.afbraco.com.br\/blog\/tag\/beneficios-da-visao-artificial-na-industria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.afbraco.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Benef\u00edcios da vis\u00e3o artificial na ind\u00fastria"}]},{"@type":"WebSite","@id":"https:\/\/www.afbraco.com.br\/blog\/#website","url":"https:\/\/www.afbraco.com.br\/blog\/","name":"Blog AF Braco","description":"","publisher":{"@id":"https:\/\/www.afbraco.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.afbraco.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.afbraco.com.br\/blog\/#organization","name":"Blog AF Braco","url":"https:\/\/www.afbraco.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.afbraco.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.afbraco.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-5.png","contentUrl":"https:\/\/www.afbraco.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-5.png","width":830,"height":234,"caption":"Blog AF Braco"},"image":{"@id":"https:\/\/www.afbraco.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.afbraco.com.br\/blog\/wp-json\/wp\/v2\/tags\/875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.afbraco.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.afbraco.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.afbraco.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}